{"id":778,"date":"2014-05-08T00:00:00","date_gmt":"2014-05-07T22:00:00","guid":{"rendered":"http:\/\/anto.cssrevolt.com\/dine-with-the-winegrower\/"},"modified":"2017-12-19T19:37:33","modified_gmt":"2017-12-19T18:37:33","slug":"dine-with-the-winegrower","status":"publish","type":"post","link":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/","title":{"rendered":"Dine with the winegrower"},"content":{"rendered":"<p><b><i>Saturday 24.05.2014<\/i><\/b><br \/>\n<b>Dine with the winegrower<\/b><br \/>\nSaturday 24th May at 19.30, an evening dedicated to the harmony of food and wine. \u20ac 45,00.<br \/>\nBy reservation only &#8211; Tel. 0742.379158,<br \/>\ne-mail: wendy@antonellisanmarco.it<br \/>\n(A guided tour of the wine cellar takes place at 19.00).<\/p>\n<p><b><i>MEN\u00d9<\/i><\/b><br \/>\n<b><i>Antipasto &#8211; Starter<\/i><\/b> <b>Grechetto dei Colli Martani DOC BIO 2013<\/b><br \/>\nPizza alla contadina \u2013 <i>Country-style pizza<\/i> Pecorino fresco con marmellata di Sagrantino \u2013 <i>Sheep\u2019s milk cheese with Sagrantino jam<\/i> Peperone arrosto \u2013 <i>Roast peppers<\/i> Rocciata salata agli spinaci e ricotta \u2013 <i>Spinach &amp; ricotta strudel<\/i> Lonza stagionata \u2013 <i>Cured pork loin<\/i> Insalata di ceci Antonelli \u2013 <i>Chickpea salad<\/i> Focaccia al rosmarino \u2013 <i>Rosemary focaccia<\/i><br \/>\n<b><i>Primo &#8211; First Course<\/i><\/b> <b>Montefalco Rosso DOC 2010<\/b><br \/>\nLinguine di farro Antonelli con guanciale e pecorino<i>Antonelli\u2019s emmer wheat linguine pasta with bacon &amp; pecorino<\/i><br \/>\n<b><i>Secondo &#8211; Second Course<\/i><\/b> <b>Montefalco Sagrantino DOCG 2007<\/b><br \/>\nAgnello arrosto \u2013 <i>Roast lamb<\/i> Costine di maiale e salsicce \u2013 <i>Pork spare ribs &amp; sausages<\/i> Patate al forno \u2013 <i>Roast potatoes<\/i> Fagiolini alla mentuccia \u2013 <i>French beans with mint<\/i> Insalatina dell&#8217;ortolano \u2013 <i>Salad<\/i><br \/>\n<b><i>Dolce &#8211; Dessert<\/i><\/b> <b>Montefalco Sagrantino Passito DOCG 2007<\/b><br \/>\nPanna cotta alla salsa di fragole \u2013 <i>Panna cotta with strawberry coulis<\/i> Biscotti al Sagrantino \u2013 <i>Sagrantino wine biscuits<\/i> Caff\u00e8 Grappa di Sagrantino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saturday 24.05.2014 Dine with the winegrower Saturday 24th May at 19.30, an evening dedicated to the harmony of food and wine. \u20ac 45,00. By reservation only &#8211; Tel. 0742.379158, e-mail: wendy@antonellisanmarco.it (A guided tour of the wine cellar takes place at 19.00). MEN\u00d9 Antipasto &#8211; Starter Grechetto dei Colli Martani DOC BIO 2013 Pizza alla [&hellip;]\n","protected":false},"author":2,"featured_media":445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,9],"tags":[],"class_list":["post-778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-news-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dine with the winegrower - Antonelli Montefalco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dine with the winegrower - Antonelli Montefalco\" \/>\n<meta property=\"og:description\" content=\"Saturday 24.05.2014 Dine with the winegrower Saturday 24th May at 19.30, an evening dedicated to the harmony of food and wine. \u20ac 45,00. By reservation only &#8211; Tel. 0742.379158, e-mail: wendy@antonellisanmarco.it (A guided tour of the wine cellar takes place at 19.00). MEN\u00d9 Antipasto &#8211; Starter Grechetto dei Colli Martani DOC BIO 2013 Pizza alla [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\" \/>\n<meta property=\"og:site_name\" content=\"Antonelli Montefalco\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-07T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-19T18:37:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"166\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mbaldovin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mbaldovin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\"},\"author\":{\"name\":\"mbaldovin\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/#\/schema\/person\/360836a334dd4492e8ffd1be478939b0\"},\"headline\":\"Dine with the winegrower\",\"datePublished\":\"2014-05-07T22:00:00+00:00\",\"dateModified\":\"2017-12-19T18:37:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\"},\"wordCount\":189,\"publisher\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png\",\"articleSection\":[\"Events\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\",\"url\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\",\"name\":\"Dine with the winegrower - Antonelli Montefalco\",\"isPartOf\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png\",\"datePublished\":\"2014-05-07T22:00:00+00:00\",\"dateModified\":\"2017-12-19T18:37:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage\",\"url\":\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png\",\"contentUrl\":\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png\",\"width\":166,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.antonellisanmarco.it\/en\/antonelli-montefalco\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dine with the winegrower\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/#website\",\"url\":\"https:\/\/www.antonellisanmarco.it\/\",\"name\":\"Antonelli Montefalco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.antonellisanmarco.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/#organization\",\"name\":\"Antonelli San Marco\",\"url\":\"https:\/\/www.antonellisanmarco.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2020\/02\/logo-antonelli-san-marco-1.jpg\",\"contentUrl\":\"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2020\/02\/logo-antonelli-san-marco-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Antonelli San Marco\"},\"image\":{\"@id\":\"https:\/\/www.antonellisanmarco.it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/#\/schema\/person\/360836a334dd4492e8ffd1be478939b0\",\"name\":\"mbaldovin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.antonellisanmarco.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c96c1bb60f4a7e18934ffc24ef248d42?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c96c1bb60f4a7e18934ffc24ef248d42?s=96&d=mm&r=g\",\"caption\":\"mbaldovin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dine with the winegrower - Antonelli Montefalco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/","og_locale":"en_US","og_type":"article","og_title":"Dine with the winegrower - Antonelli Montefalco","og_description":"Saturday 24.05.2014 Dine with the winegrower Saturday 24th May at 19.30, an evening dedicated to the harmony of food and wine. \u20ac 45,00. By reservation only &#8211; Tel. 0742.379158, e-mail: wendy@antonellisanmarco.it (A guided tour of the wine cellar takes place at 19.00). MEN\u00d9 Antipasto &#8211; Starter Grechetto dei Colli Martani DOC BIO 2013 Pizza alla [&hellip;]","og_url":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/","og_site_name":"Antonelli Montefalco","article_published_time":"2014-05-07T22:00:00+00:00","article_modified_time":"2017-12-19T18:37:33+00:00","og_image":[{"width":166,"height":166,"url":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png","type":"image\/png"}],"author":"mbaldovin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mbaldovin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#article","isPartOf":{"@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/"},"author":{"name":"mbaldovin","@id":"https:\/\/www.antonellisanmarco.it\/#\/schema\/person\/360836a334dd4492e8ffd1be478939b0"},"headline":"Dine with the winegrower","datePublished":"2014-05-07T22:00:00+00:00","dateModified":"2017-12-19T18:37:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/"},"wordCount":189,"publisher":{"@id":"https:\/\/www.antonellisanmarco.it\/#organization"},"image":{"@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png","articleSection":["Events","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/","url":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/","name":"Dine with the winegrower - Antonelli Montefalco","isPartOf":{"@id":"https:\/\/www.antonellisanmarco.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage"},"image":{"@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png","datePublished":"2014-05-07T22:00:00+00:00","dateModified":"2017-12-19T18:37:33+00:00","breadcrumb":{"@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#primaryimage","url":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png","contentUrl":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2017\/12\/cena-vignaiolo.png","width":166,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.antonellisanmarco.it\/en\/dine-with-the-winegrower\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.antonellisanmarco.it\/en\/antonelli-montefalco\/"},{"@type":"ListItem","position":2,"name":"Dine with the winegrower"}]},{"@type":"WebSite","@id":"https:\/\/www.antonellisanmarco.it\/#website","url":"https:\/\/www.antonellisanmarco.it\/","name":"Antonelli Montefalco","description":"","publisher":{"@id":"https:\/\/www.antonellisanmarco.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.antonellisanmarco.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.antonellisanmarco.it\/#organization","name":"Antonelli San Marco","url":"https:\/\/www.antonellisanmarco.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.antonellisanmarco.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2020\/02\/logo-antonelli-san-marco-1.jpg","contentUrl":"https:\/\/www.antonellisanmarco.it\/wp-content\/uploads\/2020\/02\/logo-antonelli-san-marco-1.jpg","width":512,"height":512,"caption":"Antonelli San Marco"},"image":{"@id":"https:\/\/www.antonellisanmarco.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.antonellisanmarco.it\/#\/schema\/person\/360836a334dd4492e8ffd1be478939b0","name":"mbaldovin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.antonellisanmarco.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c96c1bb60f4a7e18934ffc24ef248d42?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c96c1bb60f4a7e18934ffc24ef248d42?s=96&d=mm&r=g","caption":"mbaldovin"}}]}},"_links":{"self":[{"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/posts\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":1,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":1044,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/posts\/778\/revisions\/1044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/media\/445"}],"wp:attachment":[{"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.antonellisanmarco.it\/en\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}